{"id":2903,"date":"2024-05-14T11:05:40","date_gmt":"2024-05-14T09:05:40","guid":{"rendered":"https:\/\/dreher-holzerzeugnisse.com\/produkt\/wooden-box-for-storage-purposes\/"},"modified":"2024-05-14T11:05:40","modified_gmt":"2024-05-14T09:05:40","slug":"wooden-box-for-storage-purposes","status":"publish","type":"dreher-produkte","link":"https:\/\/dreher-holzerzeugnisse.com\/en\/produkt\/wooden-box-for-storage-purposes\/","title":{"rendered":"Wooden box for storage purposes"},"excerpt":{"rendered":"<p>Wooden box in plywood design with sliding lid, surface painted in opaque color<\/p>\n","protected":false},"featured_media":2583,"template":"","wt_produktkategorie":[36],"class_list":["post-2903","dreher-produkte","type-dreher-produkte","status-publish","has-post-thumbnail","hentry","wt_produktkategorie-wooden-caskets"],"_links":{"self":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte\/2903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte"}],"about":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/types\/dreher-produkte"}],"version-history":[{"count":0,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte\/2903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/media\/2583"}],"wp:attachment":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/media?parent=2903"}],"wp:term":[{"taxonomy":"wt_produktkategorie","embeddable":true,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/wt_produktkategorie?post=2903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}