{"id":2921,"date":"2024-05-14T09:55:00","date_gmt":"2024-05-14T07:55:00","guid":{"rendered":"https:\/\/dreher-holzerzeugnisse.com\/produkt\/wooden-case-for-cigars\/"},"modified":"2024-05-14T09:55:00","modified_gmt":"2024-05-14T07:55:00","slug":"wooden-case-for-cigars","status":"publish","type":"dreher-produkte","link":"https:\/\/dreher-holzerzeugnisse.com\/en\/produkt\/wooden-case-for-cigars\/","title":{"rendered":"Wooden case for cigars"},"excerpt":{"rendered":"<p>Wooden case in solid wood design with hinged lid, surface cleanly sanded, with magnetic catch and recessed grip, lower and upper part made entirely of solid wood with milled recesses<\/p>\n","protected":false},"featured_media":424,"template":"","wt_produktkategorie":[37],"class_list":["post-2921","dreher-produkte","type-dreher-produkte","status-publish","has-post-thumbnail","hentry","wt_produktkategorie-wooden-cases"],"_links":{"self":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte\/2921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte"}],"about":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/types\/dreher-produkte"}],"version-history":[{"count":0,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/dreher-produkte\/2921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/media\/424"}],"wp:attachment":[{"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/media?parent=2921"}],"wp:term":[{"taxonomy":"wt_produktkategorie","embeddable":true,"href":"https:\/\/dreher-holzerzeugnisse.com\/en\/wp-json\/wp\/v2\/wt_produktkategorie?post=2921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}